{"id":8191,"date":"2019-12-17T17:14:21","date_gmt":"2019-12-18T01:14:21","guid":{"rendered":"http:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166.jpg"},"modified":"2019-12-17T17:14:21","modified_gmt":"2019-12-18T01:14:21","slug":"sam_1166","status":"inherit","type":"attachment","link":"https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1166\/","title":{"rendered":"SAM_1166"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-8191","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-560x315.jpg 560w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":4320,"height":2432,"file":"2019\/12\/SAM_1166.jpg","sizes":{"thumbnail":{"file":"SAM_1166-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-150x150.jpg"},"medium":{"file":"SAM_1166-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-300x169.jpg"},"medium_large":{"file":"SAM_1166-768x432.jpg","width":768,"height":432,"mime_type":"image\/jpeg","source_url":"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-768x432.jpg"},"large":{"file":"SAM_1166-1024x576.jpg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-1024x576.jpg"},"xs-thumb":{"file":"SAM_1166-64x64.jpg","width":64,"height":64,"mime_type":"image\/jpeg","source_url":"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-64x64.jpg"},"post-thumbnail":{"file":"SAM_1166-672x372.jpg","width":672,"height":372,"mime_type":"image\/jpeg","source_url":"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-672x372.jpg"},"twentyfourteen-full-width":{"file":"SAM_1166-1038x576.jpg","width":1038,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-1038x576.jpg"},"mailchimp":{"file":"SAM_1166-560x315.jpg","width":560,"height":315,"mime_type":"image\/jpeg","source_url":"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-560x315.jpg"},"full":{"file":"SAM_1166.jpg","width":4320,"height":2432,"mime_type":"image\/jpeg","source_url":"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166.jpg"}},"image_meta":{"aperture":"4.6","credit":"","camera":"WB150 \/ WB150F \/ WB152 \/ WB152F \/ WB151 \/ WB151F","caption":"","created_timestamp":"1378994557","copyright":"COPYRIGHT, 2010","focal_length":"19.5","iso":"80","shutter_speed":"0.0111111111111","title":"","orientation":"1"}},"post":8176,"source_url":"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166.jpg","_links":{"self":[{"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/media\/8191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":8176,"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/pages\/8176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}