{"id":8176,"date":"2020-10-23T08:10:10","date_gmt":"2020-10-23T15:10:10","guid":{"rendered":"http:\/\/larryeifert.com\/?page_id=8176"},"modified":"2021-07-06T09:42:24","modified_gmt":"2021-07-06T16:42:24","slug":"2013-9-royal-basin-olympic-national-park","status":"publish","type":"page","link":"https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/","title":{"rendered":"2019-9 Royal Basin Olympic National Park"},"content":{"rendered":"<p>Royal Basin, Olympic National Park is just 25 miles from our home here in Port Townsend Washington. No art, just a nice hike with Nancy.<\/p>\n<div id='gallery-1' class='gallery galleryid-8176 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1108\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1108-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1108-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1108-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1108-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1108-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1131\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1131-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1131-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1131-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1131-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1131-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/river-camp\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/River-camp-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/River-camp-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/River-camp-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/River-camp-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/River-camp-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/feet-fire-and-creek\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Feet-Fire-and-Creek-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Feet-Fire-and-Creek-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Feet-Fire-and-Creek-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Feet-Fire-and-Creek-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Feet-Fire-and-Creek-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1105\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1105-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1105-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1105-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1105-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1105-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1139\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1139-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1139-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1139-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1139-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1139-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1250\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"356\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1250-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1250-1024x768.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1250-300x225.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1250-768x576.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1250-560x420.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1122\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1122-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1122-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1122-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1122-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1122-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/old-tree\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Old-tree-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Old-tree-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Old-tree-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Old-tree-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Old-tree-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1246\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"356\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1246-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1246-1024x768.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1246-300x225.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1246-768x576.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1246-560x420.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1165\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1165-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1165-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1165-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1165-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1165-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1166\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1166-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/royal-lake-and-mt-fricaba\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Lake-and-Mt-Fricaba-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Lake-and-Mt-Fricaba-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Lake-and-Mt-Fricaba-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Lake-and-Mt-Fricaba-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Lake-and-Mt-Fricaba-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/breakfast\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Breakfast-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Breakfast-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Breakfast-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Breakfast-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Breakfast-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1143\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1143-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1143-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1143-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1143-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1143-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/royal-falls\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"632\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Falls-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Falls-768x1024.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Falls-225x300.jpg 225w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Falls-560x747.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/lower-royal-falls\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"356\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Lower-Royal-Falls-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Lower-Royal-Falls-1024x768.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Lower-Royal-Falls-300x225.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Lower-Royal-Falls-768x576.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Lower-Royal-Falls-560x420.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1207\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1207-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1207-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1207-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1207-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1207-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/morning-starbucks-and-cream\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"297\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Morning-Starbucks-and-cream-1024x642.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Morning-Starbucks-and-cream-1024x642.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Morning-Starbucks-and-cream-300x188.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Morning-Starbucks-and-cream-768x482.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Morning-Starbucks-and-cream-560x351.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/royal-lake-sunset\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"843\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Lake-sunset-576x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Lake-sunset-576x1024.jpg 576w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Lake-sunset-169x300.jpg 169w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Lake-sunset-768x1364.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/Royal-Lake-sunset-560x995.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1194\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"267\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1194-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1194-1024x576.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1194-300x169.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1194-768x432.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1194-560x315.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1229\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"356\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1229-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1229-1024x768.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1229-300x225.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1229-768x576.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1229-560x420.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/larryeifert.com\/wordpress\/hiking-journals\/2013-9-royal-basin-olympic-national-park\/sam_1235\/'><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"356\" src=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1235-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1235-1024x768.jpg 1024w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1235-300x225.jpg 300w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1235-768x576.jpg 768w, https:\/\/larryeifert.com\/wordpress\/wp-content\/uploads\/2019\/12\/SAM_1235-560x420.jpg 560w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Royal Basin, Olympic National Park is just 25 miles from our home here in Port Townsend Washington. No art, just a nice hike with Nancy.<\/p>\n","protected":false},"author":1,"featured_media":8188,"parent":8066,"menu_order":12,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8176","page","type-page","status-publish","has-post-thumbnail","hentry"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"_links":{"self":[{"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/pages\/8176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/comments?post=8176"}],"version-history":[{"count":4,"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/pages\/8176\/revisions"}],"predecessor-version":[{"id":9928,"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/pages\/8176\/revisions\/9928"}],"up":[{"embeddable":true,"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/pages\/8066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/media\/8188"}],"wp:attachment":[{"href":"https:\/\/larryeifert.com\/wordpress\/wp-json\/wp\/v2\/media?parent=8176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}